{"id":50,"date":"2009-11-17T15:11:52","date_gmt":"2009-11-17T13:11:52","guid":{"rendered":"https:\/\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg"},"modified":"2009-11-17T15:11:52","modified_gmt":"2009-11-17T13:11:52","slug":"pingvellir","status":"inherit","type":"attachment","link":"https:\/\/blog.biketravel.net\/en\/pingvellir\/","title":{"rendered":"Pingvellir"},"author":1346,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-50","attachment","type-attachment","status-inherit","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pingvellir - biketravel.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.biketravel.net\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/Pingvellir.jpg\",\"url\":\"https:\\\/\\\/blog.biketravel.net\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/Pingvellir.jpg\",\"name\":\"Pingvellir - biketravel.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/#website\"},\"datePublished\":\"2009-11-17T13:11:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.biketravel.net\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/Pingvellir.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.biketravel.net\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/Pingvellir.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.biketravel.net\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/Pingvellir.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pingvellir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/\",\"name\":\"Cycle the world - biketravel.net\",\"description\":\"A road full of adventures...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pingvellir - biketravel.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg","url":"https:\/\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg","name":"Pingvellir - biketravel.net","isPartOf":{"@id":"https:\/\/blog.biketravel.net\/de\/#website"},"datePublished":"2009-11-17T13:11:52+00:00","breadcrumb":{"@id":"https:\/\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.biketravel.net\/de\/"},{"@type":"ListItem","position":2,"name":"Pingvellir"}]},{"@type":"WebSite","@id":"https:\/\/blog.biketravel.net\/de\/#website","url":"https:\/\/blog.biketravel.net\/de\/","name":"Cycle the world - biketravel.net","description":"A road full of adventures...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.biketravel.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_shortlink":"https:\/\/wp.me\/acO9X7-O","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"50\" data-permalink=\"https:\/\/blog.biketravel.net\/en\/pingvellir\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Pingvellir\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?fit=1024%2C768&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":768,"file":"2009\/11\/Pingvellir.jpg","sizes":{"thumbnail":{"file":"Pingvellir-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"Pingvellir-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?fit=300%2C225&ssl=1"},"medium_large":{"file":"Pingvellir-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?fit=768%2C576&ssl=1"},"large":{"file":"Pingvellir-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?fit=1024%2C768&ssl=1"},"wptouch-new-thumbnail":{"file":"Pingvellir-144x144.jpg","width":144,"height":144,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?resize=144%2C144&ssl=1"},"tc-grid-full":{"file":"Pingvellir-1024x350.jpg","width":1024,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?resize=1024%2C350&ssl=1"},"tc-grid":{"file":"Pingvellir-570x350.jpg","width":570,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?resize=570%2C350&ssl=1"},"tc-thumb":{"file":"Pingvellir-270x250.jpg","width":270,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?resize=270%2C250&ssl=1"},"slider-full":{"file":"Pingvellir-1024x500.jpg","width":1024,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?resize=1024%2C500&ssl=1"},"slider":{"file":"Pingvellir-1024x500.jpg","width":1024,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?resize=1024%2C500&ssl=1"},"full":{"file":"Pingvellir.jpg?fit=1024%2C768&ssl=1","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg?fit=1024%2C768&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/blog.biketravel.net\/wp-content\/uploads\/2009\/11\/Pingvellir.jpg","_links":{"self":[{"href":"https:\/\/blog.biketravel.net\/en\/wp-json\/wp\/v2\/media\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.biketravel.net\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blog.biketravel.net\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blog.biketravel.net\/en\/wp-json\/wp\/v2\/users\/1346"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.biketravel.net\/en\/wp-json\/wp\/v2\/comments?post=50"}]}}