{"id":342,"count":2,"description":"","link":"https:\/\/blog.biketravel.net\/en\/tag\/navimag\/","name":"navimag","slug":"navimag","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>navimag Archives - Cycle the world - biketravel.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.biketravel.net\/de\/tag\/navimag\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/tag\\\/navimag\\\/\",\"url\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/tag\\\/navimag\\\/\",\"name\":\"navimag Archives - Cycle the world - biketravel.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/tag\\\/navimag\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/tag\\\/navimag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"navimag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/\",\"name\":\"Cycle the world - biketravel.net\",\"description\":\"A road full of adventures...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.biketravel.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"navimag Archives - Cycle the world - biketravel.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.biketravel.net\/de\/tag\/navimag\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.biketravel.net\/de\/tag\/navimag\/","url":"https:\/\/blog.biketravel.net\/de\/tag\/navimag\/","name":"navimag Archives - Cycle the world - biketravel.net","isPartOf":{"@id":"https:\/\/blog.biketravel.net\/de\/#website"},"breadcrumb":{"@id":"https:\/\/blog.biketravel.net\/de\/tag\/navimag\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.biketravel.net\/de\/tag\/navimag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.biketravel.net\/de\/"},{"@type":"ListItem","position":2,"name":"navimag"}]},{"@type":"WebSite","@id":"https:\/\/blog.biketravel.net\/de\/#website","url":"https:\/\/blog.biketravel.net\/de\/","name":"Cycle the world - biketravel.net","description":"A road full of adventures...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.biketravel.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/blog.biketravel.net\/en\/wp-json\/wp\/v2\/tags\/342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.biketravel.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.biketravel.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.biketravel.net\/en\/wp-json\/wp\/v2\/posts?tags=342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}